{"id":914,"date":"2015-09-30T17:15:17","date_gmt":"2015-09-30T15:15:17","guid":{"rendered":"http:\/\/www.studiozandegiacomo.it\/it\/?page_id=914"},"modified":"2015-09-30T17:22:37","modified_gmt":"2015-09-30T15:22:37","slug":"copyright","status":"publish","type":"page","link":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/","title":{"rendered":"Copyright"},"content":{"rendered":"<p>Testi, foto, grafica, materiali audio e video inseriti da nel sito sono di propriet\u00e0 dello Studio Zandegiacomo, nella persona del Dott. Roberto Zandegiacomo M., o in licenza d\u2019uso a lui stesso\u00a0e non potranno essere pubblicati, riscritti, commercializzati, distribuiti, radio o video trasmessi, da parte degli utenti e dei terzi in genere, in alcun modo e sotto qualsiasi forma senza l\u2019assenso esplicito ed espresso in forma scritta da parte del titolare.<\/p>\n<p>Eventuale materiale di propriet\u00e0 di terzi \u00e8 pubblicato con specifica autorizzazione che non ne consente una ulteriore diffusione ed \u00e8 pertanto soggetto alla legge sulla tutela del copyright.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Testi, foto, grafica, materiali audio e video inseriti da nel sito sono di propriet\u00e0 dello Studio Zandegiacomo, nella persona del Dott. Roberto Zandegiacomo M., o in licenza d\u2019uso a lui stesso\u00a0e non potranno essere pubblicati, riscritti, commercializzati, distribuiti, radio o video trasmessi, da parte degli utenti e dei terzi in genere, in alcun modo e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-914","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Copyright - Studio Zandegiacomo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copyright - Studio Zandegiacomo\" \/>\n<meta property=\"og:description\" content=\"Testi, foto, grafica, materiali audio e video inseriti da nel sito sono di propriet\u00e0 dello Studio Zandegiacomo, nella persona del Dott. Roberto Zandegiacomo M., o in licenza d\u2019uso a lui stesso\u00a0e non potranno essere pubblicati, riscritti, commercializzati, distribuiti, radio o video trasmessi, da parte degli utenti e dei terzi in genere, in alcun modo e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Zandegiacomo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/studiozandegiacomo\/\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-30T15:22:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/copyright\\\/\",\"url\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/copyright\\\/\",\"name\":\"Copyright - Studio Zandegiacomo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#website\"},\"datePublished\":\"2015-09-30T15:15:17+00:00\",\"dateModified\":\"2015-09-30T15:22:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/copyright\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/copyright\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/copyright\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Copyright\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/\",\"name\":\"Studio Zandegiacomo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#organization\",\"name\":\"Studio Zandegiacomo\",\"url\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo-v4.png\",\"contentUrl\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/logo-v4.png\",\"width\":313,\"height\":100,\"caption\":\"Studio Zandegiacomo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiozandegiacomo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/studiozandegiacomo\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7r_Z4stR1j9eg9wKbVyxXw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copyright - Studio Zandegiacomo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/","og_locale":"it_IT","og_type":"article","og_title":"Copyright - Studio Zandegiacomo","og_description":"Testi, foto, grafica, materiali audio e video inseriti da nel sito sono di propriet\u00e0 dello Studio Zandegiacomo, nella persona del Dott. Roberto Zandegiacomo M., o in licenza d\u2019uso a lui stesso\u00a0e non potranno essere pubblicati, riscritti, commercializzati, distribuiti, radio o video trasmessi, da parte degli utenti e dei terzi in genere, in alcun modo e [&hellip;]","og_url":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/","og_site_name":"Studio Zandegiacomo","article_publisher":"https:\/\/www.facebook.com\/studiozandegiacomo\/","article_modified_time":"2015-09-30T15:22:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/","url":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/","name":"Copyright - Studio Zandegiacomo","isPartOf":{"@id":"https:\/\/www.studiozandegiacomo.it\/it\/#website"},"datePublished":"2015-09-30T15:15:17+00:00","dateModified":"2015-09-30T15:22:37+00:00","breadcrumb":{"@id":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studiozandegiacomo.it\/it\/copyright\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.studiozandegiacomo.it\/it\/copyright\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiozandegiacomo.it\/it\/"},{"@type":"ListItem","position":2,"name":"Copyright"}]},{"@type":"WebSite","@id":"https:\/\/www.studiozandegiacomo.it\/it\/#website","url":"https:\/\/www.studiozandegiacomo.it\/it\/","name":"Studio Zandegiacomo","description":"","publisher":{"@id":"https:\/\/www.studiozandegiacomo.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiozandegiacomo.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.studiozandegiacomo.it\/it\/#organization","name":"Studio Zandegiacomo","url":"https:\/\/www.studiozandegiacomo.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.studiozandegiacomo.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.studiozandegiacomo.it\/it\/wp-content\/uploads\/2015\/07\/logo-v4.png","contentUrl":"https:\/\/www.studiozandegiacomo.it\/it\/wp-content\/uploads\/2015\/07\/logo-v4.png","width":313,"height":100,"caption":"Studio Zandegiacomo"},"image":{"@id":"https:\/\/www.studiozandegiacomo.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/studiozandegiacomo\/","https:\/\/www.youtube.com\/channel\/UC7r_Z4stR1j9eg9wKbVyxXw"]}]}},"_links":{"self":[{"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/pages\/914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/comments?post=914"}],"version-history":[{"count":2,"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/pages\/914\/revisions"}],"predecessor-version":[{"id":921,"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/pages\/914\/revisions\/921"}],"wp:attachment":[{"href":"https:\/\/www.studiozandegiacomo.it\/it\/wp-json\/wp\/v2\/media?parent=914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}